{"id":146,"date":"2015-12-15T11:39:27","date_gmt":"2015-12-15T09:39:27","guid":{"rendered":"https:\/\/steenkamper.wordpress.com\/?page_id=146"},"modified":"2026-04-28T17:40:52","modified_gmt":"2026-04-28T15:40:52","slug":"ausschuesse","status":"publish","type":"page","link":"https:\/\/www.steenkamper.de\/index.php\/ausschuesse\/","title":{"rendered":"Aussch\u00fcsse"},"content":{"rendered":"<h3>und Arbeitsgruppen (AGs)<\/h3>\n<p>Die\u00a0Vereinsarbeit der Heimst\u00e4ttervereinigung Steenkamp e.V. wird getragen\u00a0durch aktive Mitglieder. Diese\u00a0Aktivit\u00e4ten werden durch\u00a0verschiedene\u00a0Aussch\u00fcssen koordiniert.<\/p>\n<p>Sollten Sie Interesse an der Mitarbeit in einem dieser Aussch\u00fcsse haben, melden Sie sich bitte bei der entsprechenden Kontaktperson, oder wenden Sie sich direkt an den Vorstand. Per Mail\u00a0oder \u00fcber unseren Briefkasten Steenkamp 37, neben dem Steenkampsaal.<\/p>\n<p>Ist ein Ausschuss derzeit nicht t\u00e4tig, haben Sie selbstverst\u00e4ndlich die M\u00f6glichkeit, seine Arbeit wieder zu aktivieren, oder in R\u00fccksprache mit dem Vorstand selber einen Ausschuss zu gr\u00fcnden.<\/p>\n<p><strong>Planungsgruppe Sommerfest\u00a0<\/strong><em>(seit 2018)<\/em><br \/>\nChristiane Willim, Tel. 8805244\u00a0<a href=\"mailto:christianewillim@gmx.de\">christianewillim(at)gmx.de<\/a><\/p>\n<p><strong>Tanz in den Mai<br \/>\n<\/strong>Gesa Lahner-Petersen,\u00a0<a href=\"mailto:die-kleine-Imkerei@gmx.de\">die-kleine-Imkerei@gmx.de<\/a><\/p>\n<p><b><a href=\"https:\/\/www.steenkamper.de\/index.php\/ideen-plaene\/kultur\/\">Kultur-Salon (Kultur\u00a0\/ Saal\u00a0\/ Veranstaltungen)\u00a0<\/a>\u00a0<\/b><br \/>\nBarbara Feige, <a href=\"mailto:bfeige@posteo.de\">bfeige(at)posteo.de<\/a><\/p>\n<p><b><a href=\"https:\/\/www.steenkamper.de\/index.php\/ideen-plaene\/milieuschutz\/\">Baukultur<\/a>\u00a0<\/b><br \/>\nJan H. Ipach, Tel. 0179 5365977 \u00a0<a href=\"mailto:jhi@coido.de\">jhi(at)coido.de<\/a><\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/ausschuss-energie\/\">Energie<\/a><\/strong>\u00a0<em>(seit 2024) \u201eAG SteenkampEnergie\u201c<br \/>\n<\/em>Petra Reimann <a href=\"mailto:Petra_reimann@posteo.de\"><u>Petra_reimann(at)posteo.de<\/u><\/a> und Steffen Smollich <a href=\"mailto:S-smollich@web.de\">S-smollich(at)web.de<\/a><br \/>\nVerteiler an die Gruppe: <a style=\"font-size: revert;\" href=\"mailto:energie@steenkamper.de\">energie(at)steenkamper.de<\/a><\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/science-city-bahrenfeld\">Science City\u00a0und die Steenkampsiedlung<\/a>\u00a0<\/strong><em>(seit 2021)<\/em><br \/>\nAlexander Schwertner, Ebertallee 187\u00a0 Email: <a href=\"mailto:alschwert@gmx.de\">alschwert(at)gmx.de<\/a><\/p>\n<p><b><a href=\"https:\/\/www.steenkamper.de\/index.php\/ideen-plaene\/helfen-tauschen-teilen\/\">tauschen, helfen, teilen\u00a0<\/a><\/b>(Tauschh\u00e4uschen)<br \/>\nEndrik Schiemann, Tel. 0152 34287807 <a href=\"mailto:endrikschiemann@gmx.de\">endrikschiemann(at)gmx.de<\/a><\/p>\n<p><strong>Stolpersteine<br \/>\n<\/strong>Andreas Z\u00fchlke, <span dir=\"ltr\">8904068 <a href=\"mailto:zuehlke-andreas@t-online.de\">zuehlke-andreas@t-online.de<\/a><\/span><\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/fluechtlingsarbeit\/\">Fl\u00fcchtlingsarbeit<\/a><\/strong><br \/>\nFriederike Petrelli, \u00a0Tel. 31790366<br \/>\nGertrud Krapp, \u00a0Tel. 8005165<br \/>\nFriedhelm Moggert-K\u00e4geler, \u00a0Tel. 0160 99165211<\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/steenkamp-history\/\">Steenkamp History<\/a><\/strong><br \/>\nGeschichtswerkstatt im Steenkampsaal<br \/>\nSebastian Buchholz <a href=\"mailto:cortisol@web.de\" target=\"_blank\" rel=\"noreferrer noopener\" data-rich-text-format-boundary=\"true\">cortisol(at)web.de<\/a><\/p>\n<p><strong>Verkehrsausschuss &amp; Bauausschuss:<br \/>\n<\/strong>Verkehrsfragen in der Siedlung &amp;\u00a0Behandlung baulicher Angelegenheiten<br \/>\nHerr Westphal, Tel. 0172 4320440<\/p>\n<p><strong>Saalverwaltung<\/strong><br \/>\nAllg. Betreuung des Saals u. der Nebenr\u00e4ume, F\u00fchren des Saal-Terminkalenders<br \/>\n<strong>Saaldispo:<\/strong> Tel. 0176 21065400<br \/>\nClaus Thiele &#8211; E-Mail:\u00a0<a href=\"mailto:Claus.Thiele@steenkamper.de?subject=SteenkampSaal\" target=\"_blank\" rel=\"noopener noreferrer\" data-cke-saved-href=\"mailto:Claus.Thiele@steenkamper.de?subject=Sommerfest%202017\">Claus.Thiele(at)steenkamper.de<\/a><a href=\"http:\/\/mailto:%20dispo.steenkampsaal@posteo.de\"><br \/>\n<\/a>Stellvertreter: Friedhelm Moggert-K\u00e4geler<\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/mieter-und-eigentuemerausschuss\/\">Mieter- und Eigent\u00fcmerausschuss<\/a>:<\/strong><br \/>\nHilfestellung in Miet- und Eigentumsfragen<br \/>\nClaus Thiele, Tel. 0176 21065400<\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/vogelweide\/\">Vogelweide <\/a><\/strong>(Rasen m\u00e4hen)<strong><br \/>\n<\/strong>Max Lips, Tel. 659 141 32\u00a0<a href=\"mailto:steenkamper@lips100.de\">steenkamper(at)lips100.de<\/a><\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/steenkamper-medien\/\">&#8220;Der Steenkamper&#8221; und Newsletter<\/a><\/strong><br \/>\nMax Lips,\u00a0Tel. 659 141 32\u00a0<a href=\"mailto:redaktion@steenkamper.de\">redaktion(at)steenkamper.de<\/a><\/p>\n<p><strong><a href=\"https:\/\/www.steenkamper.de\/index.php\/steenkamper-medien\/\">Webseite und Server<\/a><\/strong><br \/>\nMax Lips,\u00a0Tel. 659 141 32\u00a0<a href=\"mailto:redaktion@steenkamper.de\">redaktion(at)steenkamper.de<\/a><\/p>\n<p class=\"s2\"><strong>\u00a0<\/strong><\/p>\n<p class=\"s2\"><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>und Arbeitsgruppen (AGs) Die\u00a0Vereinsarbeit der Heimst\u00e4ttervereinigung Steenkamp e.V. wird getragen\u00a0durch aktive Mitglieder. Diese\u00a0Aktivit\u00e4ten werden durch\u00a0verschiedene\u00a0Aussch\u00fcssen koordiniert. Sollten Sie Interesse an der Mitarbeit in einem dieser Aussch\u00fcsse haben, melden Sie sich [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-146","page","type-page","status-publish","hentry"],"acf":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/P74Wuo-2m","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5263,"url":"https:\/\/www.steenkamper.de\/index.php\/engagierte-nachbarn\/","url_meta":{"origin":146,"position":0},"title":"Engagierte Nachbarn","author":"Max","date":"16\/11\/2017","format":false,"excerpt":"Eine lebendige Nachbarschaft lebt von dem Engagement ihrer Bewohner. F\u00fcr eine gute Vernetzung und Koordination der vielf\u00e4ltigen Aktivit\u00e4ten unserer sehr gro\u00dfen Nachbarschaft ist die Mehrheit der Steenkamphaushalte in der Heimst\u00e4ttervereinigung\u00a0Steenkamp e.V. organisiert. W\u00e4hrend sich der Vorstand um die formalen Vereinsgesch\u00e4fte k\u00fcmmert, f\u00fcllen die Nachbarn das Ganze mit Leben. Entweder indem\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":276,"url":"https:\/\/www.steenkamper.de\/index.php\/satzung\/","url_meta":{"origin":146,"position":1},"title":"Satzung","author":"Max","date":"16\/12\/2015","format":false,"excerpt":"Satzung ge\u00e4nderte Satzung g\u00fcltig seit der Mitgliederversammlung am 6.4.2022 Pr\u00e4ambel\u00a0 W\u00e4hrend der Bauzeit der Gartenstadt Steenkamp wurde 1920 die Heimst\u00e4ttervereinigung Steenkamp als Organisation der Mieter gegr\u00fcndet. Das gesellige Miteinander zu organisieren und Hilfestellungen aller Art anzubieten, diesen Zielen ist der Verein stets verpflichtet geblieben..\u00a0 \u00a7 1 Name und Sitz\u00a0 Der\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35491,"url":"https:\/\/www.steenkamper.de\/","url_meta":{"origin":146,"position":2},"title":"guteNachbarschaft","author":"Max","date":"28\/04\/2026","format":false,"excerpt":"\u2026 in der Handyansicht sind einige Inhalte ausgeblendet. ... gute Nachbarschaft Heimst\u00e4ttervereinigung Steenkamp e.V. Mitglied werden SOMMERFEST: Infos \/ Programm \/ Hilfe-Liste Heimst\u00e4tter\u00advereinigung Steenkamp e.V. Mitglieder 0 Haushalte 0 gegr\u00fcndet 2027 Newsletter Abonnent*innen\u200b 0 *Stand Juni 2026 Nachbarschaft in der Steenkampsiedlung Die Heimst\u00e4ttervereinigung Steenkamp e.V. verbindet seit \u00fcber 100 Jahren\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2026\/05\/IMG_6877.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2026\/05\/IMG_6877.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2026\/05\/IMG_6877.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2026\/05\/IMG_6877.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":247,"url":"https:\/\/www.steenkamper.de\/index.php\/fluechtlingsarbeit\/","url_meta":{"origin":146,"position":3},"title":"Ausschuss Fl\u00fcchtlingsunterst\u00fctzung","author":"Max","date":"15\/12\/2015","format":false,"excerpt":"Caf\u00e9 VogelweideDas Caf\u00e9 ist seit April 2022 nach einer l\u00e4ngeren Coronapause wieder aktiv. Alle Steenkamper\/innen sind eingeladen mit neuen Nachbarn\/innen Deutsch zu kl\u00f6nen und zu Tee\/Kaffee\/Kuchen zusammenzusitzen. Kuchenspenden (geschnittene) sind sehr erw\u00fcnscht, um das Buffet zu erweitern. Sie k\u00f6nnen ab 15.00h abgegeben werden. Das Caf\u00e9 findet ab 16.00h bis 17.30h\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2016\/09\/IMG_2805-300x141.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17778,"url":"https:\/\/www.steenkamper.de\/index.php\/science-city-bahrenfeld\/","url_meta":{"origin":146,"position":4},"title":"Science City Bahrenfeld","author":"Max","date":"31\/12\/2021","format":false,"excerpt":"Ausschuss \u201eScience City und die Steenkampsiedlung\"Kontakt: Alexander SchwertnerEbertallee 187\u00a0 Email:\u00a0alschwert(at)gmx.de siehe \u201eDer Steenkamper\u201c Ausgabe 1\/2024 Seite 24&25 aus der Mitgliederzeitung \u201eDer Steenkamper\u201c Ausgabe 2\/2022 Seite 18 Bitte nutzt die Kommentarfunktion (unten) um wichtige Punkte noch zu erg\u00e4nzen!Damit unsere Steenkamper-Interessen mit in die Planungen einflie\u00dfen k\u00f6nnen, soll demn\u00e4chst ein Positionspapier an\u2026","rel":"","context":"Mit 1 Kommentar","block_context":{"text":"Mit 1 Kommentar","link":"https:\/\/www.steenkamper.de\/index.php\/science-city-bahrenfeld\/#comments"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2024\/01\/AusschussScienCity.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2024\/01\/AusschussScienCity.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2024\/01\/AusschussScienCity.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2024\/01\/AusschussScienCity.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2024\/01\/AusschussScienCity.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.steenkamper.de\/wp-content\/uploads\/2024\/01\/AusschussScienCity.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":35981,"url":"https:\/\/www.steenkamper.de\/index.php\/steenkampenergie-satzung\/","url_meta":{"origin":146,"position":5},"title":"SteenkampEnergie &#8211; Satzung","author":"Max","date":"22\/05\/2026","format":false,"excerpt":"Satzung des Vereins SteenkampEnergie e.V. \u00a71 NAME, SITZ UND GESCH\u00c4FTSJAHR (1) \u00a0Der Verein f\u00fchrt den Namen: SteenkampEnergie. Nach Eintragung im Vereinsregister f\u00fchrt der Verein den Zusatz \u201ee.V.\u201c (2) \u00a0Der Verein hat seinen Sitz in Hamburg, Stadtteil Bahrenfeld. (3) \u00a0Das Gesch\u00e4ftsjahr ist das Kalenderjahr. Das erste Gesch\u00e4ftsjahr ist ein Rumpfgesch\u00e4ftsjahr und\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/pages\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/comments?post=146"}],"version-history":[{"count":107,"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/pages\/146\/revisions"}],"predecessor-version":[{"id":35524,"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/pages\/146\/revisions\/35524"}],"wp:attachment":[{"href":"https:\/\/www.steenkamper.de\/index.php\/wp-json\/wp\/v2\/media?parent=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}